{"id":195,"date":"2021-05-13T12:08:57","date_gmt":"2021-05-13T15:08:57","guid":{"rendered":"https:\/\/sisvida.com.br\/?page_id=195"},"modified":"2025-10-29T16:23:40","modified_gmt":"2025-10-29T19:23:40","slug":"software","status":"publish","type":"page","link":"https:\/\/sisvida.com.br\/index.php\/software\/","title":{"rendered":"software para laborat\u00f3rio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"195\" class=\"elementor elementor-195\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bc4be97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bc4be97\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13f76145\" data-id=\"13f76145\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5292ec12 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5292ec12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"#infografico\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-images\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Veja o Infogr\u00e1fico<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-584d094c elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"584d094c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51ee34cb\" data-id=\"51ee34cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f488550 elementor-widget elementor-widget-heading\" data-id=\"4f488550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Veja como o Vida pode resolver seus problemas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de0d494 elementor-widget elementor-widget-text-editor\" data-id=\"6de0d494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O Sistema VIDA \u00e9 software para gest\u00e3o de laborat\u00f3rios de an\u00e1lises cl\u00ednicas que come\u00e7ou a ser desenvolvido pela Techmobil no ano de 2008.<\/p><p>Ap\u00f3s dois anos de pesquisa e desenvolvimento com a participa\u00e7\u00e3o de profissionais das diversas \u00e1reas que envolvem o Laborat\u00f3rio de An\u00e1lises Cl\u00ednicas, desde a recep\u00e7\u00e3o, passando pelo faturamento, at\u00e9 o setor t\u00e9cnico, o VIDA entrou em produ\u00e7\u00e3o em Janeiro de 2010 no primeiro laborat\u00f3rio, ampliando para mais 4 nos primeiros 10 meses.<\/p><p>De l\u00e1 at\u00e9 aqui, s\u00e3o mais de 15 anos no mercado. O VIDA se espalhou por todo o Brasil, s\u00e3o mais de 600 clientes por todo o Brasil, atendendo laborat\u00f3rios do Rio Grande do Sul ao Amap\u00e1, do Acre \u00e0 Para\u00edba.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11835840 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"11835840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"#detalhes\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Detalhes do Sistema<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76ccb455 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"76ccb455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-543d7a81\" data-id=\"543d7a81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e31b15 elementor-widget elementor-widget-image\" data-id=\"2e31b15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"684\" height=\"480\" src=\"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png\" class=\"attachment-full size-full wp-image-197\" alt=\"\" srcset=\"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png 684w, https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3-300x211.png 300w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-191d4d6d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"191d4d6d\" data-element_type=\"section\" data-e-type=\"section\" id=\"infografico\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c6dabd6\" data-id=\"7c6dabd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c15cbf elementor-widget elementor-widget-image\" data-id=\"70c15cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/apresentacaoplanejadorweb.com.br\/sis_vida\/wp-content\/uploads\/2021\/05\/infografico.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"infografico.jpg\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTk5LCJ1cmwiOiJodHRwczpcL1wvc2lzdmlkYS5jb20uYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9pbmZvZ3JhZmljby5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/infografico-1024x853.jpg\" class=\"attachment-large size-large wp-image-199\" alt=\"\" srcset=\"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/infografico-1024x853.jpg 1024w, https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/infografico-300x250.jpg 300w, https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/infografico-768x640.jpg 768w, https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/infografico.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77718d67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77718d67\" data-element_type=\"section\" data-e-type=\"section\" id=\"detalhes\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44b34ecb\" data-id=\"44b34ecb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-569262d8 elementor-widget elementor-widget-heading\" data-id=\"569262d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Detalhes do Sistema<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6dde80fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dde80fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75a7a72b\" data-id=\"75a7a72b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-306054eb elementor-widget elementor-widget-text-editor\" data-id=\"306054eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Recep\u00e7\u00e3o<\/strong><\/p><p>Para Recep\u00e7\u00e3o o VIDA oferece recursos fundamentais para o trabalho \u00e1gil e sem erros. Com uma poderosa ferramenta de busca do paciente, que localiza qualquer parte do nome digitado, o tamb\u00e9m o n\u00famero do documento, o sistema evita a duplica\u00e7\u00e3o de cadastros mantendo o hist\u00f3rico dos pacientes. Al\u00e9m disso, a detec\u00e7\u00e3o inteligente de duplica\u00e7\u00f5es verifica nomes parecidos com a mesma data de nascimento informada e alerta o usu\u00e1rio sobre a exist\u00eancia de um cadastro anterior.<\/p><p>Integra\u00e7\u00f5es para autoriza\u00e7\u00e3o de atendimentos de conv\u00eanios diminuem erros e reduzem o tempo de atendimento. O VIDA pega as autoriza\u00e7\u00f5es automaticamente com o servidor do conv\u00eanio que disponibilizam o servi\u00e7o, j\u00e1 gerando as guias com as senhas de autoriza\u00e7\u00e3o. Al\u00e9m disso, as valida\u00e7\u00f5es para campos obrigat\u00f3rios para cada conv\u00eanio diminuem glosas e agilizam a gera\u00e7\u00e3o das faturas no final do m\u00eas.<\/p><p>Com o controle individual de caixa, cada recepcionista ficar\u00e1 respons\u00e1vel pelos recebimentos que faz, facilitando assim o controle por parte dos gestores. Todos os dados adicionados ou modificados sobre pagamentos, descontos, modifica\u00e7\u00f5es de conv\u00eanios e outras informa\u00e7\u00f5es, ficam registrados no VIDA para efeito de auditoria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e7ce7cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e7ce7cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7eeb67de\" data-id=\"7eeb67de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb39014 elementor-widget elementor-widget-text-editor\" data-id=\"fb39014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00c1rea T\u00e9cnica<\/strong><\/p><p>Interfaceamento com os principais laborat\u00f3rios de apoio, \u00c1lvaro, Hermes Pardini e DB Diagn\u00f3stico. Facilidade para envio das amostras, sem necessidade de redigitar informa\u00e7\u00f5es dos pacientes no sistema do laborat\u00f3rio de apoio. O recebimento de resultados \u00e9 completo, retornando para cada laudo al\u00e9m dos resultados, a metodologia, valores de refer\u00eancia, unidades de medida, notas e observa\u00e7\u00f5es. N\u00e3o \u00e9 necess\u00e1rio ficar atualizando manualmente essas informa\u00e7\u00f5es de forma manual.<\/p><p>Com o Interfaceamento com Equipamentos, os resultados s\u00e3o lan\u00e7ados automaticamente no VIDA, diminuindo erro na transcri\u00e7\u00e3o de resultados e agilizando a realiza\u00e7\u00e3o dos exames.<\/p><p>Gera\u00e7\u00e3o de Mapas de Trabalho para cada setor, organizando o trabalho nas bancadas e tamb\u00e9m agilizando o lan\u00e7amento de resultados.<\/p><p>A assinatura eletr\u00f4nica dos laudos d\u00e1 liberdade aos analistas, que podem realizar a libera\u00e7\u00e3o dos exames de qualquer lugar que estiverem, utilizando a facilidade que o VIDA oferece por ser um sistema 100% WEB. Na libera\u00e7\u00e3o, o analista tem acesso a todas as informa\u00e7\u00f5es do paciente, incluindo todo hist\u00f3rico de resultados dos exames que est\u00e3o sendo liberados.<\/p><p>Rastreabilidade completa, todas as etapas de realiza\u00e7\u00e3o dos exames s\u00e3o rastreadas, gravando o usu\u00e1rio, data e hora de realiza\u00e7\u00e3o de cada etapa. Altera\u00e7\u00f5es em resultados tamb\u00e9m s\u00e3o registradas ficando armazenado tamb\u00e9m os que sofreram mudan\u00e7as e quem modificou.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39d6c898 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39d6c898\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-684bad67\" data-id=\"684bad67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a805c89 elementor-widget elementor-widget-text-editor\" data-id=\"a805c89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Soroteca<\/strong><\/p><p>Os materiais coletados dos pacientes podem ser armazenados e controlados atrav\u00e9s da soroteca, facilitando a localiza\u00e7\u00e3o dos materiais quando necess\u00e1rio e informando os que j\u00e1 podem ser expurgados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b353d33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b353d33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6d297fc2\" data-id=\"6d297fc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e2c1d29 elementor-widget elementor-widget-text-editor\" data-id=\"1e2c1d29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Coleta<\/strong><\/p><p>Todas as amostras s\u00e3o identificadas com c\u00f3digos de barras, evitando erros de troca de amostras. As informa\u00e7\u00f5es de material, tubo a ser coletado, nome do paciente, sexo, idade e exames a serem feitos, s\u00e3o impressas na etiqueta para orientar na coleta.<\/p><p>O Registro de coleta \u00e9 realizado de forma eletr\u00f4nica, atrav\u00e9s dos c\u00f3digos de barras, identificando quem coletou as amostras, data e hora.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5881fa0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5881fa0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59068866\" data-id=\"59068866\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bed576b elementor-widget elementor-widget-text-editor\" data-id=\"6bed576b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Estoque<\/strong><\/p><p>Na parte de estoque o VIDA possui ferramenta de solicita\u00e7\u00e3o de materiais, sendo poss\u00edvel para os usu\u00e1rios solicitarem o que necessitam e o respons\u00e1vel pelo estoque ir\u00e1 avaliar e atender as solicita\u00e7\u00f5es dando baixa autom\u00e1tica no estoque. Todas as solicita\u00e7\u00f5es ficam registradas. Al\u00e9m disso todas as ferramentas para o controle do estoque de materiais, com avisos sobre o ponto m\u00ednimo e relat\u00f3rios de utiliza\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b4b14ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b4b14ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-34892d3d\" data-id=\"34892d3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73857692 elementor-widget elementor-widget-text-editor\" data-id=\"73857692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Gestor<\/strong><\/p><p>Todos os controles realizados pelo VIDA possuem o objetivo de gerar as informa\u00e7\u00f5es que os Gestores ir\u00e3o precisar para an\u00e1lise, planejamento e tomada de decis\u00f5es. Relat\u00f3rios das \u00e1reas Financeira, Faturamento, T\u00e9cnica e Qualidade, ir\u00e3o fornecer as ferramentas fundamentais para uma gest\u00e3o eficiente e focada em resultados.<\/p><p>Al\u00e9m dos relat\u00f3rios, possui as ferramentas de rastreabilidade e controle das altera\u00e7\u00f5es realizadas em pagamentos de atendimentos, modifica\u00e7\u00f5es de conv\u00eanios de atendimentos e o fechamento de caixa individualizado por recepcionista. As informa\u00e7\u00f5es importantes ficam gravadas no sistema e as altera\u00e7\u00f5es s\u00e3o auditadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39c7c55f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39c7c55f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-332be76\" data-id=\"332be76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2348b391 elementor-widget elementor-widget-text-editor\" data-id=\"2348b391\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Faturamento Eletr\u00f4nico<\/strong><\/p><p>Na \u00e1rea de Faturamento o VIDA possui a gera\u00e7\u00e3o de arquivos XML da TISS e BPA do SUS. Reduzindo em muito o tempo de fechamento e envio das faturas.<\/p><p>Com o controle de Pr\u00e9-Fatura, os atendimentos dos conv\u00eanios ficam em uma \u00e1rea para verifica\u00e7\u00e3o, sendo poss\u00edvel bloquear a impress\u00e3o de resultados at\u00e9 que o atendimento seja conferido pela Pr\u00e9-Fatura. Essa rotina evita problemas ao final do m\u00eas na gera\u00e7\u00e3o da fatura.<\/p><p>H\u00e1 tamb\u00e9m o controle de faturas enviadas, dando baixa nos pagamentos realizados pelas operadoras, informando as despesas e reten\u00e7\u00f5es da fatura e tamb\u00e9m informando as Glosas da fatura. As glosas ficam registradas e possuem um controle espec\u00edfico para o acompanhamento e recupera\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Veja o Infogr\u00e1fico Veja como o Vida pode resolver seus problemas O Sistema VIDA \u00e9 software para gest\u00e3o de laborat\u00f3rios de an\u00e1lises cl\u00ednicas que come\u00e7ou a ser desenvolvido pela Techmobil no ano de 2008. Ap\u00f3s dois anos de pesquisa e desenvolvimento com a participa\u00e7\u00e3o de profissionais das diversas \u00e1reas que envolvem o Laborat\u00f3rio de An\u00e1lises [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"disabled","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"disabled","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-195","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>software para laborat\u00f3rio - VIDA - Software para Laborat\u00f3rio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sisvida.com.br\/index.php\/software\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"software para laborat\u00f3rio\" \/>\n<meta property=\"og:description\" content=\"Veja o Infogr\u00e1fico Veja como o Vida pode resolver seus problemas O Sistema VIDA \u00e9 software para gest\u00e3o de laborat\u00f3rios de an\u00e1lises cl\u00ednicas que come\u00e7ou a ser desenvolvido pela Techmobil no ano de 2008. Ap\u00f3s dois anos de pesquisa e desenvolvimento com a participa\u00e7\u00e3o de profissionais das diversas \u00e1reas que envolvem o Laborat\u00f3rio de An\u00e1lises [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sisvida.com.br\/index.php\/software\/\" \/>\n<meta property=\"og:site_name\" content=\"VIDA - Software para Laborat\u00f3rio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T19:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/\",\"url\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/\",\"name\":\"software para laborat\u00f3rio - VIDA - Software para Laborat\u00f3rio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sisvida.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/escolhida3.png\",\"datePublished\":\"2021-05-13T15:08:57+00:00\",\"dateModified\":\"2025-10-29T19:23:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sisvida.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/escolhida3.png\",\"contentUrl\":\"https:\\\/\\\/sisvida.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/escolhida3.png\",\"width\":684,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/index.php\\\/software\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sisvida.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"software para laborat\u00f3rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#website\",\"url\":\"https:\\\/\\\/sisvida.com.br\\\/\",\"name\":\"VIDA - Software para Laborat\u00f3rio\",\"description\":\"Software para Laborat\u00f3rio 100% Web\",\"publisher\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sisvida.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#organization\",\"name\":\"VIDA - Software para Laborat\u00f3rio\",\"url\":\"https:\\\/\\\/sisvida.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sisvida.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/sisvida.com.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo@2x.png\",\"width\":600,\"height\":153,\"caption\":\"VIDA - Software para Laborat\u00f3rio\"},\"image\":{\"@id\":\"https:\\\/\\\/sisvida.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"software para laborat\u00f3rio - VIDA - Software para Laborat\u00f3rio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sisvida.com.br\/index.php\/software\/","og_locale":"pt_BR","og_type":"article","og_title":"software para laborat\u00f3rio","og_description":"Veja o Infogr\u00e1fico Veja como o Vida pode resolver seus problemas O Sistema VIDA \u00e9 software para gest\u00e3o de laborat\u00f3rios de an\u00e1lises cl\u00ednicas que come\u00e7ou a ser desenvolvido pela Techmobil no ano de 2008. Ap\u00f3s dois anos de pesquisa e desenvolvimento com a participa\u00e7\u00e3o de profissionais das diversas \u00e1reas que envolvem o Laborat\u00f3rio de An\u00e1lises [&hellip;]","og_url":"https:\/\/sisvida.com.br\/index.php\/software\/","og_site_name":"VIDA - Software para Laborat\u00f3rio","article_modified_time":"2025-10-29T19:23:40+00:00","og_image":[{"url":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sisvida.com.br\/index.php\/software\/","url":"https:\/\/sisvida.com.br\/index.php\/software\/","name":"software para laborat\u00f3rio - VIDA - Software para Laborat\u00f3rio","isPartOf":{"@id":"https:\/\/sisvida.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sisvida.com.br\/index.php\/software\/#primaryimage"},"image":{"@id":"https:\/\/sisvida.com.br\/index.php\/software\/#primaryimage"},"thumbnailUrl":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png","datePublished":"2021-05-13T15:08:57+00:00","dateModified":"2025-10-29T19:23:40+00:00","breadcrumb":{"@id":"https:\/\/sisvida.com.br\/index.php\/software\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sisvida.com.br\/index.php\/software\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sisvida.com.br\/index.php\/software\/#primaryimage","url":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png","contentUrl":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/05\/escolhida3.png","width":684,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/sisvida.com.br\/index.php\/software\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sisvida.com.br\/"},{"@type":"ListItem","position":2,"name":"software para laborat\u00f3rio"}]},{"@type":"WebSite","@id":"https:\/\/sisvida.com.br\/#website","url":"https:\/\/sisvida.com.br\/","name":"VIDA - Software para Laborat\u00f3rio","description":"Software para Laborat\u00f3rio 100% Web","publisher":{"@id":"https:\/\/sisvida.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sisvida.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sisvida.com.br\/#organization","name":"VIDA - Software para Laborat\u00f3rio","url":"https:\/\/sisvida.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sisvida.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/03\/logo@2x.png","contentUrl":"https:\/\/sisvida.com.br\/wp-content\/uploads\/2021\/03\/logo@2x.png","width":600,"height":153,"caption":"VIDA - Software para Laborat\u00f3rio"},"image":{"@id":"https:\/\/sisvida.com.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/pages\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":38,"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/pages\/195\/revisions"}],"predecessor-version":[{"id":1678,"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/pages\/195\/revisions\/1678"}],"wp:attachment":[{"href":"https:\/\/sisvida.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}